{"id":26161,"date":"2024-08-08T13:07:26","date_gmt":"2024-08-08T11:07:26","guid":{"rendered":"https:\/\/www.act-translations.com\/erfolgreiche-uebersetzung-von-websites\/"},"modified":"2024-09-04T09:14:04","modified_gmt":"2024-09-04T07:14:04","slug":"erfolgreiche-uebersetzung-von-websites","status":"publish","type":"post","link":"https:\/\/www.act-translations.com\/de-at\/erfolgreiche-uebersetzung-von-websites\/","title":{"rendered":"Erfolgreiche \u00dcbersetzung von Websites: 7 Tipps, mit denen Sie garantiert richtig verstanden werden"},"content":{"rendered":"\n<p><strong>Websites zu \u00fcbersetzen, das klingt einfach. Ist es aber nicht ganz. Es gibt gute Gr\u00fcnde, diese Aufgabe den Profis zu \u00fcberlassen, da maschinelle \u00dcbersetzung oft nicht den kontextuellen und sprachlichen Anforderungen gerecht wird. Worauf Sie bei der Wahl des Dienstleisters achten sollten und was Sie selbst zum Gelingen beitragen k\u00f6nnen, haben wir hier zusammengefasst.<\/strong><\/p>\n\n\n\n<p>Erinnern Sie sich noch? Die Website, hie\u00df es vor nicht allzu langer Zeit, sei die Visitenkarte des Unternehmens. Stimmt schon. Und dennoch ist sie viel mehr. Unternehmens-Websites sind die erste Anlaufstelle f\u00fcr jede Art von Interaktion; hier werden die Weichen gestellt f\u00fcr alles, was folgt: Information, Erstkontakt, Kundenbindung, Sales, Kritik und Feedback, Suche nach Mitarbeiter:innen. <a href=\"https:\/\/www.act-translations.com\/de-at\/sprachdienstleistungen\/webseite-uebersetzen\/\" data-type=\"link\" data-id=\"https:\/\/www.act-translations.com\/de-de\/sprachdienstleistungen\/webseite-uebersetzen\/\">Die Website ist Teil des Brandings<\/a>\u00a0ebenso wie des Employer Brandings, sie beeinflusst in den meisten F\u00e4llen den Grundton einer gelingenden Beziehung.<\/p>\n\n\n\n<p><strong>Sorgf\u00e4ltige \u00dcbersetzungen \u00f6ffnen T\u00fcren<\/strong><\/p>\n\n\n\n<p>Warum es sinnvoll ist, dieses m\u00e4chtige Tool nicht nur in der eigenen Sprache anzubieten? Dazu einige <a href=\"https:\/\/brightplugins.com\/de\/seo-statistics-for-multilingual-websites\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fakten<\/a>.<\/p>\n\n\n\n<p>Fast zwei Drittel der User:innen bevorzugen laut globaler Umfragen den Besuch von Websites in ihrer Muttersprache.<\/p>\n\n\n\n<p>Der Einsatz einer mehrsprachigen Website steigert nachweislich sowohl Conversion Rates als auch Online-Verk\u00e4ufe.<\/p>\n\n\n\n<p>\u00dcbersetzung ist auch hochgradig relevant f\u00fcr die Suchmaschinenoptimierung: Sie f\u00fchrt zu einer gr\u00f6\u00dferen Zahl indizierbarer Seiten und erh\u00f6ht die Sichtbarkeit in der organischen Suche, was f\u00fcr Ihre Marke und den Markt von Vorteil ist.<\/p>\n\n\n\n<p>Mehrsprachige Inhalte werden auf Social Media rund doppelt so h\u00e4ufig geteilt.<\/p>\n\n\n\n<p>Nicht zuletzt: Nur rund f\u00fcnf Prozent aller Websites sind mehrsprachig \u2013 sie bieten daher einen klaren Wettbewerbsvorteil.<\/p>\n\n\n\n<p>Nicht jede Website bedarf der \u00dcbersetzung. Wer seine Zielgruppen ausschlie\u00dflich im Inland oder sogar nur lokal sieht, muss nicht auf Englisch kommunizieren k\u00f6nnen. F\u00fcr alle anderen gilt jedoch: Mehrsprachigkeit \u00f6ffnet viele T\u00fcren.<\/p>\n\n\n\n<p><strong>5 gute Gr\u00fcnde, Profis mit der \u00dcbersetzung von Websites zu beauftragen \u2026<\/strong><\/p>\n\n\n\n<p>Ein paar Buttons, die eine oder andere \u00dcberschrift und einige Zeilen Text ins Englische zu \u00fcbertragen, das schaffen auch <a href=\"https:\/\/www.act-translations.com\/de-at\/beste-wordpress-uebersetzungs-plugins\/\" data-type=\"link\" data-id=\"https:\/\/www.act-translations.com\/de-de\/beste-wordpress-uebersetzungs-plugins\/\">\u00dcbersetzungstools<\/a>\u00a0oder die Kollegin mit Fremdsprachenkenntnis unfallfrei. Doch viel spricht daf\u00fcr, komplexere Aufgaben denen zu \u00fcbergeben, die es wirklich k\u00f6nnen. Auf diese Aspekte sollten Sie bei der Auswahl Ihres \u00dcbersetzungsservice achten, um sicherzustellen, dass Ihr Content markenkonform und f\u00fcr Suchmaschinen optimiert ist:<\/p>\n\n\n\n<p><strong>1.&nbsp;&nbsp;&nbsp; Profis haben Insider-Wissen<\/strong><\/p>\n\n\n\n<p>In Ihrer Branche gibt es nicht nur Fachwissen \u2013 auch die Sprache weist Spezifika auf. Professionelle \u00dcbersetzungsdienstleister besch\u00e4ftigen Mitarbeiter:innen, die auf verschiedene Branchen spezialisiert und dementsprechend bewandert in deren Terminologie sind. Doch hier geht es nicht nur um einzelne Ausdr\u00fccke: Die Kenntnis der Branche umfasst auch das Wissen um die Bedingungen und die Usancen dieser Branche im jeweiligen Zielland. Nicht zuletzt das Wissen darum, wie der Mitbewerb des Auftraggebers seine Online-Pr\u00e4senz gestaltet.<\/p>\n\n\n\n<p><strong>2.&nbsp;&nbsp;&nbsp; Profis sind kulturell versiert<\/strong><\/p>\n\n\n\n<p>Der Aspekt der Kultur geht \u00fcber Fachterminologie nat\u00fcrlich weit hinaus. Sprachbilder, Vergleiche, Wortspiele und nicht zuletzt Humor: All das kann bei w\u00f6rtlicher \u00dcbersetzung sein Ziel verfehlen, zu Missverst\u00e4ndnissen f\u00fchren oder im schlimmsten Fall beleidigend sein. Das gleiche gilt f\u00fcr die verwendeten Fotos, die man m\u00f6glicherweise adaptieren oder ersetzen sollte. \u00dcbersetzungen von Websites verlangen also mehr als die Transkription von Text: Es geht auch um die Ann\u00e4herung an eine andere Kultur. Gute \u00dcbersetzer:innen verf\u00fcgen nicht nur \u00fcber exzellente Sprachkenntnisse, sondern \u00fcber tiefes Wissen um jede Nuance in der Kultur des Ziellandes. Nur \u00fcber kulturelle Nuancen gelingt echte Lokalisierung.<\/p>\n\n\n\n<p><strong>3.&nbsp; &nbsp; Profis kennen die Rechtslagen<\/strong><\/p>\n\n\n\n<p>Websites sind nicht zuletzt eines: eine Sammlung von Dokumenten mit juristischer Bedeutung. Vom Impressum und kleinen Disclaimern \u00fcber auszuf\u00fcllende Formulare bis hin zu ausf\u00fchrlichen AGB \u2013 die rechtlichen Grundlagen variieren zum Teil massiv. Sich hier Schnitzer zu erlauben, kann potenziell katastrophale Folgen f\u00fcr die Betreiber der Website haben. Das Engagement professioneller \u00dcbersetzungsb\u00fcros ist vor allem auch in diesem Bereich von entscheidender Bedeutung. Hier arbeiten Menschen, die auch \u00fcber die rechtlichen Gegebenheiten des Ziellandes genau Bescheid wissen beziehungsweise Kontakte zu den richtigen Juristinnen und Juristen haben.<\/p>\n\n\n\n<p><strong>4. &nbsp; Profis beherrschen die Technik<\/strong><\/p>\n\n\n\n<p>Die \u00dcbersetzung von Websites kann selbstverst\u00e4ndlich erfolgen, indem man Word-Dokumente im Kreis schickt. Besser ist es aber, wenn die \u00dcbersetzer:innen direkt mit den entsprechenden Tools arbeiten. Mit anderen Worten: Sie m\u00fcssen sattelfest sein im Umgang mit Contentmanagement-Systemen und anderer Technologie. Eine weitere ratsame Expertise, die man bei den Profis findet.<\/p>\n\n\n\n<p><strong>5.&nbsp; &nbsp;Profis denken strategisch<\/strong><\/p>\n\n\n\n<p>Websites h\u00e4ngen (hoffentlich) nicht im luftleeren Raum, sie sind im Kontext einer Gesamtstrategie des Unternehmens zu sehen. Die Qualit\u00e4t im Prozess der \u00dcbersetzung h\u00e4ngt auch davon ab, inwieweit die Dienstleister in der Lage sind, in solchen Konzepten zu denken und zu agieren. Das ist, zugegeben, auch Bringschuld des Auftraggebers: Je besser das Briefing und je intensiver die Insights in die Ziele des Unternehmens sind, desto fruchtbarer wird die Zusammenarbeit beim \u00dcbersetzen ausfallen.<\/p>\n\n\n\n<p><strong>\u2026 und zwei Dinge, die Sie vorbereiten k\u00f6nnen<\/strong><\/p>\n\n\n\n<p>Sie haben Ihren Dienstleister f\u00fcr das \u00dcbersetzungsprojekt gefunden? Wunderbar! Zwei Aufgaben sollten Sie allerdings im Vorfeld erledigen, damit das Erstellen Ihrer neuen Website in der neuen Sprache ein echter Erfolg wird.&nbsp;<\/p>\n\n\n\n<p><strong>1.&nbsp;&nbsp;&nbsp; Sorgen Sie f\u00fcr hochwertige Ausgangstexte!<\/strong><\/p>\n\n\n\n<p>Schlechte Texte werden durch \u00dcbersetzung nicht zu guten Texten. Fehler in Orthografie oder Syntax m\u00f6gen so verschwinden, doch die beiden wesentlichen Anforderungen m\u00fcssen schon davor erf\u00fcllt sein: Storytelling und Struktur im Content.<\/p>\n\n\n\n<p>Gutes Storytelling ist nicht den gro\u00dfen Geschichten vorbehalten. Auch auf kleinem Raum, in kurzer Form ist es m\u00f6glich, eine Story rund um sein Unternehmen, dessen Produkte oder Dienstleistungen zu spinnen. Je h\u00e4ufiger Sie dabei Superlative und platte Werbebotschaften durch Esprit, Humor und Fantasie ersetzen, desto mehr werden Ihre Texte zu Geschichten.<\/p>\n\n\n\n<p>Genauso wichtig ist die Struktur der Website, die sich immer auch in den Texten spiegelt. Im Idealfall durchlaufen Besucher:innen die Miniaturform einer Customer Journey, werden so intuitiv wie m\u00f6glich dorthin geleitet, wo ihr Ziel liegt \u2013 aber auch dorthin, wo das Ziel Ihres Unternehmens liegt. Damit das gelingt, ist klare und stringente Sprache genauso wichtig wie der technische Aufbau der Website.<\/p>\n\n\n\n<p>Als Nebenaspekt des guten Ausgangstexts kann man auch den Domainnamen verstehen: Sollten Sie die Domain im Wissen einrichten, dass sie zwei- oder mehrsprachig sein wird, empfiehlt sich ein englischer Domainname.<\/p>\n\n\n\n<p><strong>2.&nbsp;&nbsp;&nbsp; W\u00e4hlen Sie die Zielsprachen gut aus!<\/strong><\/p>\n\n\n\n<p>Panini-Alben sollten m\u00f6glichst gut gef\u00fcllt sein. F\u00fcr die Sprachauswahl Ihrer Website gilt das nicht. Eine \u00dcbersetzung in m\u00f6glichst \u201eexotische\u201c Sprachen, die f\u00fcr Ihre Zielgruppe v\u00f6llig uninteressant sind, wirkt nicht weltm\u00e4nnisch, sondern im schlimmsten Fall pr\u00e4potent.<\/p>\n\n\n\n<p>In den meisten F\u00e4llen wird Englisch wohl die Zielsprache Nummer Eins sein, wenn es um Internationalisierung geht. Alles, was dar\u00fcber hinausgeht, ist von eingehender Analyse der eigenen Zielgruppe abh\u00e4ngig \u2013 beziehungsweise von der Strategie, diese zu erweitern. Hilfreich ist hier auch eine eingehende Analyse des bisherigen Traffics auf der Website beziehungsweise der verschiedenen KPIs in den Social Media, um den Markt besser zu verstehen.<\/p>\n\n\n\n<p>In vielen Branchen (und manchen L\u00e4ndern) ist Englisch eine Lingua Franca. Ist dies nicht der Fall, muss eine andere Sprache gew\u00e4hlt werden. In L\u00e4ndern wie der Schweiz oder Belgien vielleicht sogar mehr als eine.<\/p>\n\n\n\n<p><a id=\"_msocom_1\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Websites zu \u00fcbersetzen, das klingt einfach. Ist es aber nicht ganz. Es gibt gute Gr\u00fcnde, diese Aufgabe den Profis zu \u00fcberlassen, da maschinelle \u00dcbersetzung oft nicht den kontextuellen und sprachlichen Anforderungen gerecht wird. Worauf Sie bei der Wahl des Dienstleisters achten sollten und was Sie selbst zum Gelingen beitragen k\u00f6nnen, haben wir hier zusammengefasst. Erinnern\u2026<\/p>\n","protected":false},"author":7,"featured_media":25086,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1051,1104],"tags":[],"class_list":["post-26161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uebersetzung-de-at","category-webseite-uebersetzen-de-at"],"_links":{"self":[{"href":"https:\/\/www.act-translations.com\/de-at\/wp-json\/wp\/v2\/posts\/26161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.act-translations.com\/de-at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.act-translations.com\/de-at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.act-translations.com\/de-at\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.act-translations.com\/de-at\/wp-json\/wp\/v2\/comments?post=26161"}],"version-history":[{"count":1,"href":"https:\/\/www.act-translations.com\/de-at\/wp-json\/wp\/v2\/posts\/26161\/revisions"}],"predecessor-version":[{"id":26309,"href":"https:\/\/www.act-translations.com\/de-at\/wp-json\/wp\/v2\/posts\/26161\/revisions\/26309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.act-translations.com\/de-at\/wp-json\/wp\/v2\/media\/25086"}],"wp:attachment":[{"href":"https:\/\/www.act-translations.com\/de-at\/wp-json\/wp\/v2\/media?parent=26161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.act-translations.com\/de-at\/wp-json\/wp\/v2\/categories?post=26161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.act-translations.com\/de-at\/wp-json\/wp\/v2\/tags?post=26161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}